{"id":34,"count":3,"description":"","link":"https:\/\/demoapus2.com\/yozi\/yozi1\/category\/new\/","name":"New","slug":"new","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/demoapus2.com\/yozi\/yozi1\/wp-json\/wp\/v2\/categories\/34"}],"collection":[{"href":"https:\/\/demoapus2.com\/yozi\/yozi1\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/demoapus2.com\/yozi\/yozi1\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/demoapus2.com\/yozi\/yozi1\/wp-json\/wp\/v2\/posts?categories=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}