{"id":37,"count":1,"description":"","link":"https:\/\/demoapus2.com\/yozi\/yozi1\/category\/laptop-accessories\/","name":"Laptop Accessories","slug":"laptop-accessories","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/demoapus2.com\/yozi\/yozi1\/wp-json\/wp\/v2\/categories\/37"}],"collection":[{"href":"https:\/\/demoapus2.com\/yozi\/yozi1\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/demoapus2.com\/yozi\/yozi1\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/demoapus2.com\/yozi\/yozi1\/wp-json\/wp\/v2\/posts?categories=37"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}